{"id":21387,"date":"2020-12-02T10:36:41","date_gmt":"2020-12-02T09:36:41","guid":{"rendered":"https:\/\/www.ripess.eu\/?p=21387"},"modified":"2022-06-02T16:54:45","modified_gmt":"2022-06-02T15:54:45","slug":"zoom-in-on-the-brussels-bubble","status":"publish","type":"post","link":"https:\/\/ripess.eu\/fr\/zoom-in-on-the-brussels-bubble\/","title":{"rendered":"Zoom sur la bulle bruxelloise"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Par Judith Hitchman, Urgenci, Pr\u00e9sidente du Comit\u00e9 International.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Il est notoirement difficile de mener des actions de plaidoyer \u00e0 Bruxelles sans y baser une personne d\u00e9di\u00e9e \u00e0 cette t\u00e2che. Et pour un r\u00e9seau comme URGENCI, c&rsquo;est un probl\u00e8me, car le plaidoyer de questions politiques cl\u00e9s telles que l&rsquo;agro\u00e9cologie et l&rsquo;importance des cha\u00eenes d&rsquo;approvisionnement alimentaire courtes dans le cadre de l&rsquo;initiative \u00ab\u00a0Farm to Fork\u00a0\u00bb (de la ferme \u00e0 la table), du \u00ab\u00a0Green Deal\u00a0\u00bb ou de la PAC sont une partie importante de notre mission europ\u00e9enne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est pourquoi nous sommes profond\u00e9ment engag\u00e9s depuis un certain temps dans le travail collectif IPES-Food sur ces sujets. Tout a commenc\u00e9 avec notre investissement collectif dans le processus de 3 ans d\u00e9velopp\u00e9 par Olivier De Schutter et son \u00e9quipe sur la strat\u00e9gie de la Politique Alimentaire Commune.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois achev\u00e9 et pr\u00e9sent\u00e9 \u00e0 la Commission, le processus est devenu la Coalition pour la politique alimentaire de l&rsquo;UE. Cette coalition est organis\u00e9e sous les auspices de Slow Food, et rassemble toutes les diff\u00e9rentes organisations de la soci\u00e9t\u00e9 civile, y compris les ONG de la bulle bruxelloise ainsi que la coordination europ\u00e9enne Via Campesina et Urgenci. Les nombreuses \u00e9quipes de travail et groupes de travail sont g\u00e9r\u00e9s par ceux et celles qui ont les ressources n\u00e9cessaires pour le faire, et la coordination g\u00e9n\u00e9rale est assur\u00e9e par Ines Jordana, avec le Bureau Ex\u00e9cutif (compos\u00e9 par IPES-Food, IFOAM Organics EU, Slow Food, EPHA, SAFE, ECVC et le EEB)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme nous pensons que les citoyen.ne.s europ\u00e9en.ne.s doivent \u00eatre au c\u0153ur des changements politiques pour que certaines opportunit\u00e9s (comme la strat\u00e9gie \u00ab\u00a0de la ferme \u00e0 la table\u00a0\u00bb) deviennent des engagements forts en faveur d&rsquo;une r\u00e9elle durabilit\u00e9 des syst\u00e8mes alimentaires, les CSOs et les mouvements qui canalisent les convictions des citoyens et la science ind\u00e9pendamment des lobbies des entreprises ont un r\u00f4le \u00e9norme \u00e0 jouer dans les discussions et la conception des politiques relatives aux syst\u00e8mes alimentaires. Il est essentiel que les Organisations de la Soci\u00e9t\u00e9 Civile (OSCs)  puissent coordonner des messages solides, clairs et collectifs. La Coalition pour la politique alimentaire de l&rsquo;UE joue un r\u00f4le unique en ce sens et peut avoir un impact d\u00e9cisif en soutenant le travail des OSCs pour concevoir et mettre en \u0153uvre les politiques de l&rsquo;UE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;av\u00e8nement de l&rsquo;actuelle pand\u00e9mie Covid-19 a eu des r\u00e9percussions tr\u00e8s int\u00e9ressantes sur la mani\u00e8re dont tout cela fonctionne et sur les effets collat\u00e9raux. Soudain, apr\u00e8s avoir fait partie des quelques participant.es distants aux r\u00e9unions qui se d\u00e9roulaient dans l&rsquo;atmosph\u00e8re cosy de Bruxelles, tout le monde travaillait depuis chez lui et sur un pied d&rsquo;\u00e9galit\u00e9. Et bien que le travail de l&rsquo;IPES-Food ait toujours essay\u00e9 d&rsquo;inclure toutes les participations \u00e0  distance, il y avait toujours un l\u00e9ger sentiment d&rsquo;\u00eatre l&rsquo;outsider. Ce n&rsquo;est plus le cas. Le fait qu&rsquo;il n&rsquo;y ait plus de possibilit\u00e9s de bavardage dans la salle avant ou apr\u00e8s les r\u00e9unions, a rendu les appels des diff\u00e9rents groupes de travail beaucoup plus \u00e9galitaires pour tous et toutes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a \u00e9galement eu un changement de m\u00e9thodologie qui rend la participation \u00e0 distance via Zoom d&rsquo;autant plus participative. Par exemple, des r\u00e9unions sp\u00e9ciales sont organis\u00e9es avec les d\u00e9put\u00e9s europ\u00e9ens pour mettre en avant nos points sp\u00e9cifiques sur les questions politiques. Ces r\u00e9unions sont pr\u00e9c\u00e9d\u00e9es et suivies d&rsquo;un travail collectif sur les documents. Non seulement la m\u00e9thodologie est inclusive et ouverte, mais elle est aussi r\u00e9ellement coop\u00e9rative et sinc\u00e8re dans la mani\u00e8re dont les diff\u00e9rents participant.es s&rsquo;accommodent des diff\u00e9rences des autres et s&rsquo;alignent solidairement sur des points de vue communs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La communication et le partage tr\u00e8s clairs et transparents de tous les documents ont \u00e9galement soutenu ce travail et ces efforts collectifs. Ce sont en grande partie les comp\u00e9tences exceptionnelles dont Ines a fait preuve pour mobiliser et rassembler tous ces efforts collectifs qui ont permis aux organisations de la soci\u00e9t\u00e9 civile de se mobiliser collectivement contre les puissants lobbies industriels (c&rsquo;est-\u00e0-dire le COPA COGECA, les entreprises ax\u00e9es sur le march\u00e9, etc. Oui, la voix de l&rsquo;industrie continue de crier \u00e0 l&rsquo;oreille des d\u00e9put\u00e9s europ\u00e9ens, mais la voix collective de la soci\u00e9t\u00e9 civile organis\u00e9e a \u00e9galement un impact croissant, m\u00eame en ces temps difficiles. Peu importe o\u00f9 nous vivons, nous pouvons tous maintenant zoomer sur Bruxelles !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Judith Hitchman, Urgenci, Pr\u00e9sidente du Comit\u00e9 International. Il est notoirement difficile de mener des actions de plaidoyer \u00e0 Bruxelles sans y baser une personne d\u00e9di\u00e9e \u00e0 cette t\u00e2che. Et [&hellip;]<\/p>\n","protected":false},"author":7021,"featured_media":21385,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","wds_primary_category":0,"footnotes":""},"categories":[8471],"tags":[],"class_list":["post-21387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-du-reseau","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/posts\/21387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/comments?post=21387"}],"version-history":[{"count":1,"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/posts\/21387\/revisions"}],"predecessor-version":[{"id":23414,"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/posts\/21387\/revisions\/23414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/media\/21385"}],"wp:attachment":[{"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/media?parent=21387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/categories?post=21387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ripess.eu\/fr\/wp-json\/wp\/v2\/tags?post=21387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}