{"id":337858,"date":"2024-06-04T08:53:17","date_gmt":"2024-06-04T06:53:17","guid":{"rendered":"https:\/\/ripess.eu\/encuentro-europeo-de-ecoaldeas-2024\/"},"modified":"2024-06-04T09:39:03","modified_gmt":"2024-06-04T07:39:03","slug":"encuentro-europeo-de-ecoaldeas-2024","status":"publish","type":"post","link":"https:\/\/ripess.eu\/es\/encuentro-europeo-de-ecoaldeas-2024\/","title":{"rendered":"Encuentro Europeo de Ecoaldeas 2024"},"content":{"rendered":"<p><em>Fuente: <a href=\"https:\/\/ecovillagegathering.org\/\">https:\/\/ecovillagegathering.org\/<\/a><\/em><\/p>\n<p>Cada a\u00f1o, cientos de personas de todo el mundo se sienten atra\u00eddas por la llamada de la comunidad a reunirse en el Encuentro Europeo de Ecoaldeas. Este festival de vida en ecoaldeas celebra la comunidad en todas sus formas y ofrece a todxs lxs asistentes la oportunidad de conocer a los ecoaldeanxs, aprender herramientas para el desarrollo comunitario, establecer contactos con almas de ideas afines y descubrir pr\u00e1cticas para la regeneraci\u00f3n social, econ\u00f3mica, cultural y ecol\u00f3gica.<br \/>\nLos preciados recuerdos de la \u00faltima visita del Encuentro a Angsbacka en 2017 todav\u00eda resuenan con calidez y alegr\u00eda en nuestros corazones. \u00a1\u00danase a nosotros para celebrar esta reuni\u00f3n y la promesa de un futuro m\u00e1s brillante y verde juntos!<\/p>\n<p><strong>Qu\u00e9 esperar<\/strong><br \/>\nEste a\u00f1o, el Encuentro extiende una invitaci\u00f3n a abrazar el acto radical de reducir la velocidad. Haremos una pausa juntxs, sintonizando con el ritmo de nuestros cuerpos, las voces de nuestra comunidad global y los susurros del mundo m\u00e1s que humano que nos rodea.<\/p>\n<p>Viaja con nosotrxs mientras cambiamos urgentemente de marcha para alejarnos del ritmo implacable dictado por el capitalismo y el consumismo. Este Encuentro es un santuario para aprender, escuchar atentamente, celebrar la belleza de la conexi\u00f3n y explorar caminos que conduzcan a patrones y estructuras constructivas y co-creadas.<\/p>\n<p>Sum\u00e9rgete en la desaceleraci\u00f3n intencional que define el Encuentro de este a\u00f1o. Descubre el profundo sentido de comunidad que surge cuando cultivamos la lentitud, la amplitud y la paciencia. Insp\u00edrate en las ecoaldeas y las comunidades conscientes, aprovechando las fuentes de sabidur\u00eda regenerativa que alimentan nuestro viaje colectivo.<\/p>\n<p><strong>El programa<\/strong><br \/>\nEl <a href=\"https:\/\/ecovillagegathering.org\/\">Encuentro Europeo de Ecoaldeas<\/a> presenta un programa de ponentes invitados, talleres co-creados y experiencias colectivas facilitadas que re\u00fanen lo mejor de la sabidur\u00eda de las ecoaldeas y las pr\u00e1cticas regenerativas.<br \/>\nLe espera un programa verdaderamente \u00fanico de&#8230;<\/p>\n<ul>\n<li>Ponentes que invitan a la reflexi\u00f3n para provocar la reflexi\u00f3n, la conversaci\u00f3n y la acci\u00f3n<\/li>\n<li>Pr\u00e1cticas encarnadas para arraigar y reconectar<\/li>\n<li>M\u00fasica y danza en las impresionantes instalaciones de nuestro recinto<\/li>\n<li>Conoce las Ecoaldeas, un espacio para descubrir las ecoaldeas de Europa<\/li>\n<li>Momentos de calma para reflexionar y recargar energ\u00edas<\/li>\n<li>\u00abGrupos en casa\u00bb para anclarlos y compartir sus experiencias con un grupo peque\u00f1o a lo largo de la Reuni\u00f3n<\/li>\n<li>Conexi\u00f3n con la naturaleza en los bosques y jardines de \u00c4ngsbacka<\/li>\n<li>Y mucho m\u00e1s&#8230;<\/li>\n<\/ul>\n<p><strong>\u00bfA qui\u00e9n va dirigido?<\/strong><br \/>\nEl Encuentro es para todxs, y aspiramos a crear un evento que tenga un ambiente verdaderamente acogedor y comunitario. Familias, agricultores, artistas, activistas, pol\u00edticos, cient\u00edficos, ecoaldeanos experimentados y novatos tienen su lugar en este encuentro que combina talleres, charlas, m\u00fasica, movimiento, artes y mucho tiempo para compartir y conectarse.<\/p>\n<p><strong>Conexi\u00f3n a la Red Europea de Ecoaldeas<\/strong><br \/>\nEl Encuentro te invita a formar parte de la Red Europea de Ecoaldeas, GEN Europe. La membres\u00eda de GEN Europe le otorga acceso a horas de contenido educativo de ecoaldeas, una conexi\u00f3n m\u00e1s cercana con otros ecoaldeanos y buscadores de ecoaldeas, y mucho m\u00e1s. Para asegurar tu plaza, tendr\u00e1s que seguir tres sencillos pasos:<\/p>\n<ul>\n<li>En primer lugar, convi\u00e9rtete en miembro de GEN Europe, con precio reducido para j\u00f3venes y otros descuentos.<\/li>\n<li>En segundo lugar, compre su boleto de Gathering como un complemento a su membres\u00eda. \u00a1Cuanto antes reserves, menor ser\u00e1 el precio!<\/li>\n<li>Por \u00faltimo, asegure su comida y alojamiento directamente con Angsbacka a trav\u00e9s de nuestro sitio web y prep\u00e1rese para disfrutar de la magia del Encuentro Europeo de Ecoaldeas.<\/li>\n<\/ul>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>RIPESS Europe contribuir\u00e1 al programa del encuentro de Ecoaldeas Europeas de este a\u00f1o con los siguientes talleres.<\/p>\n<p><strong>Construyendo una comunidad alimentaria: de los productos b\u00e1sicos a los bienes comunes<\/strong><\/p>\n<p>Cualquier persona tiene derecho a alimentos saludables, de buena calidad y cultivados localmente, y este derecho es la base de cualquier comunidad. \u00bfCu\u00e1l es la relaci\u00f3n que tenemos con la tierra y c\u00f3mo la utilizamos? \u00bfQu\u00e9 relaci\u00f3n es regenerativa, sostenible, mutualista y econ\u00f3micamente viable? \u00bfC\u00f3mo hacer esto en la pr\u00e1ctica? C\u00f3mo construir una ecocomunidad desde el acceso a los alimentos y m\u00e1s all\u00e1, con pr\u00e1cticas de econom\u00eda solidaria (desde CSA hasta cooperativas de alimentos y diferentes formas de iniciativas cooperativas). \u00bfQu\u00e9 puede compartir el movimiento de ecoaldeas de sus pr\u00e1cticas? Ven y disc\u00fatelo con nosotros e intercambia ejemplos inspiradores de diferentes comunidades de toda Europa.<\/p>\n<p>Monica Onyszkiewicz, de Polonia CSA, movimiento agroecol\u00f3gico y de comercio justo, miembro del comit\u00e9 de coordinaci\u00f3n de RIPESS Europa.<\/p>\n<p><strong>Expo GEN &#8211; Comunidades Solidarias de Energ\u00edas Renovables: \u00a1poder para el pueblo!<\/strong><\/p>\n<p>Unete a nosotrxs para explorar c\u00f3mo hacer de la energ\u00eda renovable un medio econ\u00f3mico para su comunidad, democratizando la producci\u00f3n, distribuci\u00f3n y consumo de energ\u00eda de una manera mutualista y participativa. Analizaremos las normas europeas y las diferentes pr\u00e1cticas que se est\u00e1n creando en muchos pa\u00edses y la gesti\u00f3n econ\u00f3mica de una comunidad, en funci\u00f3n de sus necesidades y aspiraciones.<\/p>\n<p>Jason Nardi, RIPESS Europe &#8211; tambi\u00e9n miembro de la cooperativa energ\u00e9tica italiana \u00abE&#8217; nostra\u00bb (Nuestra energ\u00eda)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuente: https:\/\/ecovillagegathering.org\/ Cada a\u00f1o, cientos de personas de todo el mundo se sienten atra\u00eddas por la llamada de la comunidad a reunirse en el Encuentro Europeo de Ecoaldeas. Este festival [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":337855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","wds_primary_category":0,"footnotes":""},"categories":[943],"tags":[1078,7799,8683],"class_list":["post-337858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campana","tag-comunidad","tag-ecoaldeas","tag-reunion","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/337858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/comments?post=337858"}],"version-history":[{"count":4,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/337858\/revisions"}],"predecessor-version":[{"id":337907,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/337858\/revisions\/337907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/media\/337855"}],"wp:attachment":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/media?parent=337858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/categories?post=337858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/tags?post=337858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}