{"id":331974,"date":"2023-04-25T14:42:16","date_gmt":"2023-04-25T12:42:16","guid":{"rendered":"https:\/\/ripess.eu\/respeto-de-los-derechos-de-las-personas-con-discapacidad\/"},"modified":"2023-05-02T13:47:15","modified_gmt":"2023-05-02T11:47:15","slug":"respeto-de-los-derechos-de-las-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/ripess.eu\/es\/respeto-de-los-derechos-de-las-personas-con-discapacidad\/","title":{"rendered":"Respeto de los derechos de las personas con discapacidad"},"content":{"rendered":"<p>Resumen del art\u00edculo <span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/infojmoderne.com\/2023\/04\/17\/handicap-la-france-epinglee-par-le-conseil-de-leurope-pour-ses-nombreux-manquements\/\">Discapacidad: Francia condenada por el Consejo de Europa por sus muchas deficiencias<\/a><\/span><\/p>\n<p><span style=\"color: #003300\">Julien Lecot, InfoJModerne, 17 de abril de 2023<\/span><\/p>\n<p class=\"TypologyArticle__BlockContainer-sc-1vro4tp-0 gQKWhn\"><strong><span class=\"TypologyArticle__BlockSubHeadline-sc-1vro4tp-4 bHYlQv\">En una decisi\u00f3n hecha p\u00fablica el lunes 17 de abril 2023,\u00a0 el Comit\u00e9 Europeo de Derechos Sociales denuncia las m\u00faltiples violaciones por parte del Estado franc\u00e9s de los derechos y libertades de las personas con discapacidad.<\/span><\/strong><\/p>\n<p class=\"article_link\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-331943 alignright\" src=\"https:\/\/ripess.eu\/wp-content\/uploads\/sites\/4\/2023\/04\/Capture-de\u0301cran-2023-04-25-a\u0300-14.41.38-300x182.png\" alt=\"\" width=\"300\" height=\"182\" srcset=\"https:\/\/ripess.eu\/wp-content\/uploads\/sites\/4\/2023\/04\/Capture-de\u0301cran-2023-04-25-a\u0300-14.41.38-300x182.png 300w, https:\/\/ripess.eu\/wp-content\/uploads\/sites\/4\/2023\/04\/Capture-de\u0301cran-2023-04-25-a\u0300-14.41.38.png 679w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>En Francia, <span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/www.liberation.fr\/societe\/sante\/77-millions-de-francais-en-situation-de-handicap-et-93-millions-daidants-20230202_RYHDIPUFJNDJLFPY2EWIGWK4HU\/\" target=\"_blank\" rel=\"noopener\">las personas con discapacidad<\/a> <\/span>son abusadas. Su libertad y sus derechos han sido violados durante a\u00f1os, sin que, a pesar de las bonitas promesas de los sucesivos gobiernos, las cosas realmente cambien. Esta dura observaci\u00f3n no es elaborada (s\u00f3lo) por la oposici\u00f3n o las asociaciones que defienden los derechos de las personas con discapacidad, sino por el Consejo de Europa. En una decisi\u00f3n un\u00e1nime, transmitida a finales de diciembre al Estado franc\u00e9s y hecha p\u00fablica el lunes 17 de abril, que <i>Lib\u00e9ration <\/i>pudo consultar, el organismo con sede en Estrasburgo, responsable en particular de la defensa de los derechos humanos, considera que Francia descuida los derechos de las personas con discapacidad.<\/p>\n<p>Se abordaron varias deficiencias: \u00ab<i>el acceso a los servicios de asistencia social y a la asistencia financiera\u00bb y <\/i> <i> \u00abservicios sanitarios\u00bb, \u00abaccesibilidad de edificios e instalaciones\u00bb y <\/i> <i>\u00abtransporte p\u00fablico\u00bb, \u00abintegraci\u00f3n social y vida de la comunidad de personas con discapacidad\u00bb, y <\/i> <i>\u00abLa inclusi\u00f3n de ni\u00f1os, ni\u00f1as y adolescentes con discapacidad en las escuelas ordinarias\u00bb.<br \/>\n<\/i><\/p>\n<p><strong>Nota:<\/strong><\/p>\n<p>En <span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/ripess.eu\/fr\/economie-solidaire-et-objectifs-de-developpement-durable-odd\/\">iniciativas relacionadas con los ODS,<\/a><\/span> presentado por la REAS, la <a href=\"https:\/\/www.socioeco.org\/bdf_fiche-document-8958_es.html\"><span style=\"color: #0000ff\">Cooperativa de Iniciativa Social Gure Sustraia<\/span>k<\/a> en el Pa\u00eds Vasco introduce a las personas con discapacidad a la permacultura y la alimentaci\u00f3n saludable, y las capacita para convertirse en instructoras, cambiando as\u00ed la forma en que las personas ven la discapacidad.<\/p>\n<p>M\u00e1s documentaci\u00f3n sobre el papel de la ESS en relaci\u00f3n con la discapacidad, en <span style=\"color: #0000ff\"><a href=\"http:\/\/www.socioeco.org\/bdf_motcle-thema-233_es.html\">socioeco.org<\/a><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumen del art\u00edculo Discapacidad: Francia condenada por el Consejo de Europa por sus muchas deficiencias Julien Lecot, InfoJModerne, 17 de abril de 2023 En una decisi\u00f3n hecha p\u00fablica el lunes [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":332057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","wds_primary_category":0,"footnotes":""},"categories":[943],"tags":[8755],"class_list":["post-331974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campana","tag-derechos","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/331974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/comments?post=331974"}],"version-history":[{"count":5,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/331974\/revisions"}],"predecessor-version":[{"id":332060,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/331974\/revisions\/332060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/media\/332057"}],"wp:attachment":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/media?parent=331974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/categories?post=331974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/tags?post=331974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}