{"id":31893,"date":"2022-07-12T17:11:52","date_gmt":"2022-07-12T16:11:52","guid":{"rendered":"https:\/\/ripess.eu\/sin-categoria\/juventud-por-el-clima-una-experiencia-de-polonia\/"},"modified":"2022-12-07T16:41:47","modified_gmt":"2022-12-07T15:41:47","slug":"juventud-por-el-clima-una-experiencia-de-polonia","status":"publish","type":"post","link":"https:\/\/ripess.eu\/es\/juventud-por-el-clima-una-experiencia-de-polonia\/","title":{"rendered":"Juventud por el Clima: la experiencia polaca"},"content":{"rendered":"<p><em>Por Mariusz Mas\u0142osz, Polonia<\/em><\/p>\n<p><span style=\"font-weight: 400\">Lxs j\u00f3venes polacxs est\u00e1n involucradxs en el tema de la justicia social. Lxs j\u00f3venes cada vez m\u00e1s activxs organizan eventos para mostrar a los responsables de la toma de decisiones que no son indiferentes a este tema. A pesar de las muchas ocupaciones a las que se enfrentan, no se rinden acudiendo a sucesivas protestas en defensa de los valores que consideran m\u00e1s importantes. Las acciones de lxs j\u00f3venes est\u00e1n empezando a tener efecto.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Uno de los movimientos juveniles m\u00e1s reconocibles en Polonia es la Youth Climate Strike (grupo nacional polaco de Fridays For Future), del que yo mismo formo parte. Una de nuestras demandas es una <\/span><i><span style=\"font-weight: 400\">transformaci\u00f3n de la econom\u00eda<\/span><\/i><span style=\"font-weight: 400\">. Vemos que el sistema econ\u00f3mico actual basado en el crecimiento exponencial ilimitado nos est\u00e1 llevando al desastre, por lo que queremos cambiarlo por uno que sea m\u00e1s amigable con la sociedad, y a trav\u00e9s de esto tambi\u00e9n con el clima y la biodiversidad global. Fuimos de lxs primerxs en hablar sobre la interseccionalidad del cambio clim\u00e1tico: afecta b\u00e1sicamente a todas las relaciones que existen en la Tierra y (en mayor o menor medida) dependen de ellas. Muchas acciones atribuidas a los individuos son, de hecho, los efectos del sistema t\u00f3xico en el que vivimos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La econom\u00eda social y solidaria puede implementarse en varios niveles. Ya a escala local, est\u00e1n surgiendo muchas grandes iniciativas, como el Sharehouse, que est\u00e1 dise\u00f1ado para intercambiar bienes entre miembros de las comunidades locales. Tambi\u00e9n se est\u00e1n creando cooperativas de energ\u00edas renovables, como en la urbanizaci\u00f3n Wroc\u0142aw Po\u0142udnie, as\u00ed como jardines comunitarios. Tambi\u00e9n se habla cada vez m\u00e1s de compartir a nivel central.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Lxs j\u00f3venes se oponen muy a menudo al modelo neoliberal de econom\u00eda de mercado. Sus valores son el bienestar de lxs dem\u00e1s y el medio ambiente, no la b\u00fasqueda despiadada de ganancias, por lo tanto, est\u00e1n buscando alternativas que lo hagan posible. Una soluci\u00f3n es la econom\u00eda social y solidaria, a menudo sin nombre, pero que funciona en la conciencia de lxs j\u00f3venes en Polonia. El freeganismo se est\u00e1 volviendo cada vez m\u00e1s popular, lo que resulta en la creaci\u00f3n de refrigeradores sociales. Lxs j\u00f3venes (incluso aquellxs con una buena situaci\u00f3n financiera) a menudo tampoco quieren comprar cosas nuevas, prefiriendo intercambiar cosas usadas. Mucha gente compra su ropa en tiendas de segunda mano o participa en los llamados intercambios de ropa, y los grupos sobre el intercambio de cosas innecesarias tambi\u00e9n son populares. Una motivaci\u00f3n es el deseo de oponerse a las grandes corporaciones que dirigen el mundo, mientras que otra es simplemente apoyar a la comunidad local. Esto demuestra que la econom\u00eda social y solidaria puede llegar a pr\u00e1cticamente todas las personas, siempre que los argumentos sean relevantes para sus creencias.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Mariusz Mas\u0142osz, Polonia Lxs j\u00f3venes polacxs est\u00e1n involucradxs en el tema de la justicia social. Lxs j\u00f3venes cada vez m\u00e1s activxs organizan eventos para mostrar a los responsables de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":31818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","wds_primary_category":0,"footnotes":""},"categories":[2211],"tags":[8631,8516,1453],"class_list":["post-31893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-la-red-es","tag-best-of-2022-es","tag-jovenes-por-el-clima","tag-polonia","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/31893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/comments?post=31893"}],"version-history":[{"count":3,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/31893\/revisions"}],"predecessor-version":[{"id":31928,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/31893\/revisions\/31928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/media\/31818"}],"wp:attachment":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/media?parent=31893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/categories?post=31893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/tags?post=31893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}