{"id":28556,"date":"2022-01-18T10:25:27","date_gmt":"2022-01-18T09:25:27","guid":{"rendered":"https:\/\/ripess.eu\/carta-de-herramientas-digitales\/"},"modified":"2022-01-19T14:08:10","modified_gmt":"2022-01-19T13:08:10","slug":"carta-de-herramientas-digitales","status":"publish","type":"post","link":"https:\/\/ripess.eu\/es\/carta-de-herramientas-digitales\/","title":{"rendered":"Carta de herramientas digitales"},"content":{"rendered":"<h2 align=\"justify\"><i>Carta adoptada por la AG de RIPESS Europa el 10 de septiembre de 2021, Bergerie de Villarceaux.<\/i><\/h2>\n<p>RIPESS Europa y sus miembros trabajan en el desarrollo de herramientas digitales para la promoci\u00f3n de la ESS y la cooperaci\u00f3n entre actores, el respeto de la personalidad y la democracia digital: herramientas de ofim\u00e1tica y publicaci\u00f3n, centro de cartograf\u00eda, documentaci\u00f3n y almacenamiento de datos, plataforma de intercambio de bienes y servicios, etc.<\/p>\n<p>A trav\u00e9s de esta carta, afirmamos que el desarrollo de la tecnolog\u00eda digital es una parte completa de la econom\u00eda y que debemos adoptar los mismos valores y principios de la ESS en este sector que en otros sectores de la econom\u00eda. Adem\u00e1s, ante el desarrollo de nuevos gigantes inform\u00e1ticos como GAFAM, que no paran de aumentar su influencia en nuestras vidas y de apropiarse de nuestros datos en su propio beneficio, es necesario apoyar y contribuir a un sector digital libre y democr\u00e1tico que respete a todos, sirva al inter\u00e9s general y est\u00e9 en consonancia con los valores y principios de la ESS.<\/p>\n<p>&nbsp;<\/p>\n<p>Para ello, esta carta define los principios que sustentan la pr\u00e1ctica digital de la RIPESS como red internacional. Adem\u00e1s, la RIPESS anima a sus miembros, y a los miembros de sus miembros, a adoptar los siguientes principios:<\/p>\n<ul>\n<li>Desarrollo de software libre y de c\u00f3digo abierto.<\/li>\n<li>Puesta en com\u00fan de recursos y competencias, en una l\u00f3gica de co-construcci\u00f3n, basada en todos los desarrollos ya disponibles;<\/li>\n<li>L\u00f3gica de agregaci\u00f3n y no competencia entre herramientas, especialmente para los datos;<\/li>\n<li>Una gesti\u00f3n transparente de los datos personales, que permita al usuario ser soberano sobre ellos;<\/li>\n<li>Herramientas que favorezcan la transici\u00f3n ecol\u00f3gica y social, que inspiren confianza, que no est\u00e9n sujetas a plataformas especulativas y que promuevan la gobernanza democr\u00e1tica.<\/li>\n<li>Infraestructuras descentralizadas (aumentan la resiliencia);<\/li>\n<li>Mutualizaci\u00f3n de la seguridad<\/li>\n<li>Software dise\u00f1ado para estar disponible tanto en el m\u00f3vil (Android, Apple y .apk) como en la web.<\/li>\n<li>Arquitectura que permite la \u00abampliaci\u00f3n\u00bb y la replicabilidad \u00aba medida\u00bb, con un coste menor en cada regi\u00f3n del mundo.<\/li>\n<li>Universalidad t\u00e9cnica (web sem\u00e1ntica);<\/li>\n<li>Eficiencia energ\u00e9tica;<\/li>\n<li>Facilidad de uso: ergonom\u00eda, acceso r\u00e1pido a las funcionalidades.<\/li>\n<\/ul>\n<p align=\"justify\">Bajar en pdf aqu\u00ed : <a href=\"https:\/\/ripess.eu\/wp-content\/uploads\/sites\/4\/2022\/01\/charte_ripess-eu_outils_nume\u0301riques_versiondefinitiveAG2021.pdf\">charte_ripess-eu_outils_nume\u0301riques_versiondefinitiveAG2021<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carta adoptada por la AG de RIPESS Europa el 10 de septiembre de 2021, Bergerie de Villarceaux. RIPESS Europa y sus miembros trabajan en el desarrollo de herramientas digitales para [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":28601,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","wds_primary_category":0,"footnotes":""},"categories":[8339],"tags":[],"class_list":["post-28556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-plataformas-colaborativas","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/28556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/comments?post=28556"}],"version-history":[{"count":7,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/28556\/revisions"}],"predecessor-version":[{"id":28699,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/posts\/28556\/revisions\/28699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/media\/28601"}],"wp:attachment":[{"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/media?parent=28556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/categories?post=28556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ripess.eu\/es\/wp-json\/wp\/v2\/tags?post=28556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}